{"id":6730,"date":"2023-06-06T16:10:37","date_gmt":"2023-06-06T14:10:37","guid":{"rendered":"https:\/\/radio-aviva.com\/nimes\/blog\/podcast\/campus-avec-liliane-dray-stereotypes-de-genre\/"},"modified":"2023-06-06T16:10:37","modified_gmt":"2023-06-06T14:10:37","slug":"campus-avec-liliane-dray-stereotypes-de-genre","status":"publish","type":"podcast","link":"https:\/\/radio-aviva.com\/nimes\/podcast\/campus-avec-liliane-dray-stereotypes-de-genre\/","title":{"rendered":"CAMPUS &#8211; AVEC LILIANE DRAY &#8211; STEREOTYPES DE GENRE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Campus du jeudi 15 juin 2023.<\/p>\n<p>Un th\u00e8me dont on a d\u00e9j\u00e0 parl\u00e9 : Comment les st\u00e9r\u00e9otypes de genre se perp\u00e9tuent \u00e0 l\u2019\u00e9cole du style \u00ab Les maths pour les gar\u00e7ons, le fran\u00e7ais pour les filles \u00bb ?<\/p>\n<p>\u2022 Alors comment les choses ont-elles \u00e9volu\u00e9 depuis ?<\/p>\n<p>\u2022 On va commencer par distinguer les St\u00e9r\u00e9otypes de genre et les choix d\u2019orientation scolaire<\/p>\n<p>\u2022 En conclusion o\u00f9 en est-on ?<\/p>\n<p>Si ce sujet vous int\u00e9resse un article \u00e0 lire sur www.theconversation.com<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","tags":[],"podcastfilter":[220,164,165,132,221,145],"class_list":["post-6730","podcast","type-podcast","status-publish","hentry","podcastfilter-academie","podcastfilter-campus","podcastfilter-education","podcastfilter-montpellier","podcastfilter-orientation","podcastfilter-perpignan"],"_links":{"self":[{"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/podcast\/6730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/podcast\/6730\/revisions"}],"wp:attachment":[{"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/media?parent=6730"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/tags?post=6730"},{"taxonomy":"podcastfilter","embeddable":true,"href":"https:\/\/radio-aviva.com\/nimes\/wp-json\/wp\/v2\/podcastfilter?post=6730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}